{"id":334,"date":"2012-08-16T08:57:37","date_gmt":"2012-08-16T11:57:37","guid":{"rendered":"http:\/\/www.maurom.com\/blog\/?p=334"},"modified":"2017-07-05T19:46:25","modified_gmt":"2017-07-05T22:46:25","slug":"settings-de-trebuchet-en-minicm9","status":"publish","type":"post","link":"https:\/\/maurom.com\/blog\/2012\/08\/16\/settings-de-trebuchet-en-minicm9\/","title":{"rendered":"Settings de Trebuchet en MiniCM9"},"content":{"rendered":"<p>Hace unos d\u00edas volv\u00ed a utilizar el launcher Trebuchet en el celular; previamente estuve utilizando Apex Launcher, pero \u00faltimamente se est\u00e1 tornando algo lento para operar as\u00ed que decid\u00ed retornar al original de CyanogenMod9.<\/p>\n<p>Por motivos que desconozco, teniendo los dos lanzadores instalados no es posible acceder a las opciones de configuraci\u00f3n de Trebuchet, no se si se mambea el men\u00fa o qu\u00e9, pero no aparecen donde deber\u00edan aparecer. Para colmo, la b\u00fasqueda en Google me da la sensaci\u00f3n que no soy el \u00fanico al que le pasa (ver <a href=\"http:\/\/forum.cyanogenmod.com\/topic\/40262-request-cm9-trebuchet-addition\/\">forum.cyanogenmod.com<\/a> y <a href=\"http:\/\/forum.xda-developers.com\/showthread.php?t=1701652\">forum.xda-developers.com<\/a>).<\/p>\n<p>En cualquier caso, es posible salir del paso iniciando la configuraci\u00f3n desde una terminal, para ello vamos al\u00a0<em>Android Terminal Emulator<\/em>, y ejecutamos:<\/p>\n<pre>am start com.cyanogenmod.trebuchet\/.preference.Preferences<\/pre>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-337 aligncenter\" title=\"terminal\" src=\"\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/terminal.png\" alt=\"\" width=\"320\" height=\"240\" srcset=\"https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/terminal.png 320w, https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/terminal-300x225.png 300w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/><\/p>\n<p>Logrando el resultado que puede verse aqu\u00ed:<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-338 aligncenter\" title=\"settings\" src=\"\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/settings.png\" alt=\"\" width=\"240\" height=\"320\" srcset=\"https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/settings.png 240w, https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/settings-225x300.png 225w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/p>\n<p>Por cierto, estaba buscando c\u00f3mo tomar una captura de pantalla y no advert\u00ed que era tan sencillo como elegir la opci\u00f3n en el men\u00fa que aparece pulsando <em>Power<\/em>. Tonto de m\u00ed.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unos d\u00edas volv\u00ed a utilizar el launcher Trebuchet en el celular; previamente estuve utilizando Apex Launcher, pero \u00faltimamente se est\u00e1 tornando algo lento para operar as\u00ed que decid\u00ed retornar al original de CyanogenMod9. Por motivos que desconozco, teniendo los dos lanzadores instalados no es posible acceder a las opciones de configuraci\u00f3n de Trebuchet, no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[16],"_links":{"self":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/334"}],"collection":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/comments?post=334"}],"version-history":[{"count":1,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/334\/revisions"}],"predecessor-version":[{"id":1607,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/334\/revisions\/1607"}],"wp:attachment":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/media?parent=334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/categories?post=334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/tags?post=334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}