{"id":361,"date":"2012-08-27T23:35:35","date_gmt":"2012-08-28T02:35:35","guid":{"rendered":"http:\/\/www.maurom.com\/blog\/?p=361"},"modified":"2017-07-05T19:45:56","modified_gmt":"2017-07-05T22:45:56","slug":"capusotto-para-casi-todos","status":"publish","type":"post","link":"https:\/\/maurom.com\/blog\/2012\/08\/27\/capusotto-para-casi-todos\/","title":{"rendered":"Capusotto para (casi) todos"},"content":{"rendered":"<p>Ingenuo de m\u00ed, queriendo escuchar algo de buena m\u00fasica en el retorno de Peter Capusotto y sus Videos, a trav\u00e9s de <a href=\"http:\/\/www.tvpublica.com.ar\/vivo\/\">la Internete<\/a>&#8230;<\/p>\n<p>Como estaremos de complicados que hasta el logo del canal est\u00e1 en blanco y negro.<\/p>\n<p><a href=\"\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/tvpublica-crash-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-362 aligncenter\" title=\"tvpublica-crash-1\" src=\"\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/tvpublica-crash-1.png\" alt=\"\" width=\"420\" height=\"377\" srcset=\"https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/tvpublica-crash-1.png 700w, https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/tvpublica-crash-1-300x269.png 300w\" sizes=\"(max-width: 420px) 100vw, 420px\" \/><\/a><\/p>\n<p>No, ac\u00e1 hay algo que definitivamente no anda bien.<\/p>\n<p><a href=\"\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/tvpublica-crash-2.png\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-363 aligncenter\" title=\"tvpublica-crash-2\" src=\"\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/tvpublica-crash-2.png\" alt=\"\" width=\"617\" height=\"459\" srcset=\"https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/tvpublica-crash-2.png 1029w, https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/tvpublica-crash-2-300x223.png 300w, https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/08\/tvpublica-crash-2-1024x761.png 1024w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/><\/a><\/p>\n<p>Tres preguntas:<\/p>\n<ul>\n<li>Ser\u00e1 porque soy un sacr\u00edlego que se conecta por Fibertel? (aunque por Speedy tampoco anda)<\/li>\n<li>Me tendr\u00eda que haber conseguido un deco digital cuando estaban de moda, no?<\/li>\n<li>Me perd\u00ed un buen programa?<\/li>\n<\/ul>\n<p>Igual, no se compara con Casero y el viejo <a href=\"http:\/\/es.wikipedia.org\/wiki\/Cha_cha_cha_(serie_de_televisi%C3%B3n)\">Cha Cha Cha<\/a>. Juzguen ustedes mismos&#8230;<\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/KdAawBuU3bQ\" frameborder=\"0\" width=\"600\" height=\"450\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/bFIeY-6h2sc\" frameborder=\"0\" width=\"600\" height=\"450\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/sW-HaZTsduk\" frameborder=\"0\" width=\"600\" height=\"450\"><\/iframe><\/p>\n<p>Que \u00e9pocas aquellas&#8230; sniff&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingenuo de m\u00ed, queriendo escuchar algo de buena m\u00fasica en el retorno de Peter Capusotto y sus Videos, a trav\u00e9s de la Internete&#8230; Como estaremos de complicados que hasta el logo del canal est\u00e1 en blanco y negro. No, ac\u00e1 hay algo que definitivamente no anda bien. Tres preguntas: Ser\u00e1 porque soy un sacr\u00edlego que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11,19],"_links":{"self":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/361"}],"collection":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/comments?post=361"}],"version-history":[{"count":2,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/361\/revisions"}],"predecessor-version":[{"id":1606,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/361\/revisions\/1606"}],"wp:attachment":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/media?parent=361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/categories?post=361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/tags?post=361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}