{"id":83,"date":"2010-10-20T21:11:11","date_gmt":"2010-10-21T00:11:11","guid":{"rendered":"http:\/\/www.maurom.com\/wp\/?p=83"},"modified":"2012-08-15T21:05:29","modified_gmt":"2012-08-16T00:05:29","slug":"diez-sistemas-operativos-en-una-netbook","status":"publish","type":"post","link":"https:\/\/maurom.com\/blog\/2010\/10\/20\/diez-sistemas-operativos-en-una-netbook\/","title":{"rendered":"Diez sistemas operativos en una netbook"},"content":{"rendered":"<p>Mi buen amigo Efraim es de esos inform\u00e1ticos que la tienen muy pero muy clara. Es de los administradores que hacen su trabajo con seriedad, pero de forma casi imperceptible para que las redes de las organizaciones sigan funcionando a pesar de las barbaridades que se ven en los desarrollos que corren sobre ellas (y de esas an\u00e9cdotas hay para hacer un libro). Tiene, eso s\u00ed, la costumbre de exprimir al m\u00e1ximo todo hardware que pasa por sus manos; de hecho m\u00e1s de una vez lo he encontrado dejado procesando equipos una semana entera para entrenar redes neuronales.<\/p>\n<p>Entre esos arranques -que a mi no se me ocurren ni por casualidad- se pregunt\u00f3 que tal andar\u00eda una netbook con diez sistemas operativos corriendo a la vez. Nueve Ubuntu(s), para ser preciso, virtualizados con <a href=\"http:\/\/en.wikipedia.org\/wiki\/Kernel-based_Virtual_Machine\">KVM<\/a> + <a href=\"http:\/\/en.wikipedia.org\/wiki\/Kernel_SamePage_Merging_(KSM)\">KSM<\/a> sobre un Debian que act\u00faa de host, y todos al mismo tiempo y todos en una netbook. Contrario a lo que uno hubiera esperado, la verdad se la banc\u00f3 muy bien, manteniendo responsivo el escritorio, como pueden ver por la captura de pantalla (de paso, con compiz). All\u00ed est\u00e1 ingresando en uno de los virtualizados, mientras los restantes a\u00fan muestran la pantalla de inicio de sesi\u00f3n.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-83 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00457.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00457-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00458.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00458-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/pantallazo1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/pantallazo1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>Por supuesto que no es cualquier netbook; de todas las que hay en el mercado, esta belleza de Asus [ver reviews <a href=\"http:\/\/www.pcadvisor.co.uk\/reviews\/index.cfm?reviewid=3218088\">1<\/a> y <a href=\"http:\/\/netbooked.net\/netbook-reviews\/review\/asus-eee-pc-1201t-review\/\">2<\/a>] tiene un procesador de 64 bits y virtualizaci\u00f3n por hardware, lo que hace posible semejante comportamiento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mi buen amigo Efraim es de esos inform\u00e1ticos que la tienen muy pero muy clara. Es de los administradores que hacen su trabajo con seriedad, pero de forma casi imperceptible para que las redes de las organizaciones sigan funcionando a pesar de las barbaridades que se ven en los desarrollos que corren sobre ellas (y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5,17,3,14,18],"_links":{"self":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/83"}],"collection":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/comments?post=83"}],"version-history":[{"count":0,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/83\/revisions"}],"wp:attachment":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/media?parent=83"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/categories?post=83"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/tags?post=83"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}