{"id":92,"date":"2010-08-11T15:36:42","date_gmt":"2010-08-11T18:36:42","guid":{"rendered":"http:\/\/www.maurom.com\/wp\/?p=92"},"modified":"2012-05-22T11:59:45","modified_gmt":"2012-05-22T14:59:45","slug":"0x4001100200001012-o-que-te-repare-magoya","status":"publish","type":"post","link":"https:\/\/maurom.com\/blog\/2010\/08\/11\/0x4001100200001012-o-que-te-repare-magoya\/","title":{"rendered":"0x4001100200001012, o que te repare Magoya"},"content":{"rendered":"<p>Por puro divertimento se me ocurri\u00f3 iniciar en Windows para crear y probar el <strong>&#8220;Disco de Recuperaci\u00f3n del Sistema de Windows 7&#8221;<\/strong> que vino con la port\u00e1til.<\/p>\n<p>Menos mal! Porque lo que se dice &#8220;reparar&#8221;, no &#8220;repara&#8221; nada&#8230; m\u00e1s que nada devuelve este muy expl\u00edcito error:<\/p>\n<p><a href=\"http:\/\/www.maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00351_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-93\" title=\"dsc00351_2\" src=\"http:\/\/www.maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00351_2.jpg\" alt=\"\" width=\"512\" height=\"384\" srcset=\"https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00351_2.jpg 512w, https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00351_2-300x225.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/p>\n<p><span style=\"font-weight: bold;\">&#8220;Error 0x4001100200001012. Si este problema persiste, comun\u00edquese con la&#8221;<\/span><\/p>\n<p>Con la&#8230;<span style=\"font-weight: bold;\">???<\/span> Y ahora s\u00ed, <a href=\"http:\/\/www.google.com\/search?q=0x4001100200001012\">que te lo repare Magoya<\/a>&#8230;<\/p>\n<p>Por supuesto, el que quiere sufrir, que siga con lo mismo. Yo me quedo con sistemas operativos serios&#8230;<\/p>\n<p><a href=\"http:\/\/www.maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00354_2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-94\" title=\"dsc00354_2\" src=\"http:\/\/www.maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00354_2.jpg\" alt=\"\" width=\"512\" height=\"384\" srcset=\"https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00354_2.jpg 512w, https:\/\/maurom.com\/blog\/wp-content\/uploads\/2012\/05\/dsc00354_2-300x225.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por puro divertimento se me ocurri\u00f3 iniciar en Windows para crear y probar el &#8220;Disco de Recuperaci\u00f3n del Sistema de Windows 7&#8221; que vino con la port\u00e1til. Menos mal! Porque lo que se dice &#8220;reparar&#8221;, no &#8220;repara&#8221; nada&#8230; m\u00e1s que nada devuelve este muy expl\u00edcito error: &#8220;Error 0x4001100200001012. Si este problema persiste, comun\u00edquese con la&#8221; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11,14],"_links":{"self":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/92"}],"collection":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":0,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/posts\/92\/revisions"}],"wp:attachment":[{"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/media?parent=92"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/categories?post=92"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/maurom.com\/blog\/wp-json\/wp\/v2\/tags?post=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}